{"id":368,"date":"2021-11-04T14:48:35","date_gmt":"2021-11-04T13:48:35","guid":{"rendered":"https:\/\/www.fishing-star.com\/?p=368\/"},"modified":"2022-02-03T10:13:15","modified_gmt":"2022-02-03T09:13:15","slug":"welche-daiwa-rolle","status":"publish","type":"post","link":"https:\/\/www.fishing-star.com\/de\/index.php\/2021\/11\/04\/welche-daiwa-rolle\/","title":{"rendered":"Welche Daiwa-Rolle?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Hat dich auch das Angelfieber gepackt? Dann wei\u00dft du am besten, dass Angeln eine extrem spannende Aktivit\u00e4t ist. Es kann aber auch frustrierend sein, wenn du nicht den Fisch fangen kannst, den du willst. Das kann passieren, aber um das zu verhindern, solltest du dich f\u00fcr die richtige Ausr\u00fcstung entscheiden, einschlie\u00dflich der richtigen <a href=\"https:\/\/www.nootica.fr\/marque\/daiwa\/moulinet.html\">Da<\/a><a href=\"https:\/\/www.nootica.de\/marke\/daiwa-marke-angelausruestung\/daiwa-rollen.html\">iwa-Rolle<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"eine-vielzahl-von-daiwa-rollen-zur-auswahl\">Eine Vielzahl von Daiwa-Rollen zur Auswahl<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn es um Rollen geht, ist Daiwa eine der Marken, die mir sofort einf\u00e4llt. Der Angelger\u00e4tespezialist ist schon lange auf dem Markt. Es ist nicht immer einfach, die Daiwa <strong>K\u00f6derangelrolle<\/strong> zu finden, wenn du zum ersten Mal auf der Suche nach einer solchen Ausr\u00fcstung bist.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Da es m\u00fchsam w\u00e4re, alle Daiwa-Rollenmodelle durchzugehen, die es gibt, haben wir nur die besten f\u00fcr dich ausgew\u00e4hlt. Das sind die grundlegenden Rollen, die du f\u00fcr so ziemlich jede Art des Angelns verwenden kannst. Aber um die Sache zu vereinfachen, werden sie nach der Fischart eingeteilt, mit der sie sich auszeichnen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Top Modelle von Daiwa Rollen sind die <a href=\"https:\/\/www.nootica.de\/spinnrolle-daiwa-ninja-lt.html\" target=\"_blank\" rel=\"noreferrer noopener\">Daiwa Ninja<\/a>, <a href=\"https:\/\/www.nootica.de\/brandungsrolle-daiwa-emblem-surf-35.html\" target=\"_blank\" rel=\"noreferrer noopener\">Daiwa Emblem<\/a> sowie die <a href=\"https:\/\/www.nootica.de\/spod-rolle-daiwa-crosscast-carp-scw.html\" target=\"_blank\" rel=\"noreferrer noopener\">Daiwa Cross Cast<\/a> (diese kannst du perfekt mit der dazu passenden Angelrute <a href=\"https:\/\/www.nootica.de\/angelrute-karpfen-daiwa-crosscast-karpfen.html\" target=\"_blank\" rel=\"noreferrer noopener\">Daiwa Crosscast Karpfen<\/a> kombinieren. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"daiwa-rollen-fur-das-wolfsbarschangeln-empfohlen\">Daiwa-Rollen f\u00fcr das Wolfsbarschangeln empfohlen<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn du auf Wolfsbarsch angeln willst, brauchst du eine erstklassige Ausr\u00fcstung. Zumindest ist es wichtig, eine <strong>K\u00f6derrolle<\/strong> mit hoher Laufqualit\u00e4t, einer starken und langlebigen Bremse und einem geringen Gewicht zu haben. All diese Eigenschaften finden sich in den verschiedenen Modellen der Marke Daiwa wieder. Der Legalis LT 2020 ist einer von ihnen. Wenn du nach dem besten Kompromiss suchst, ist dieses Modell das Richtige f\u00fcr dich.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn du ein echter Bassfischer bist, kannst du auf ein h\u00f6herwertiges Modell umsteigen. Eine dieser Daiwa-Rollen sollte dir nicht vorenthalten werden: Fuego, Freams, Caldia und nat\u00fcrlich die Exceler. Die ultimative Bassrolle von Daiwa ist das Spitzenmodell der Luvias, Exist oder Certate.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"daiwa-rollen-fur-das-welsangeln\">Daiwa-Rollen f\u00fcr das Welsangeln<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Mit gro\u00dfer Freude drehst du die Kurbel deiner Daiwa-Rolle, um einen gro\u00dfen 80 cm langen Wels aus dem Wasser zu ziehen. Aber du musst das richtige Modell w\u00e4hlen, damit du keinen einzigen Bissen verpasst. Im Bereich der Rollen f\u00fcr das Angeln auf Wels und wels\u00e4hnliche Fische kannst du auf<a href=\"https:\/\/www.nootica.de\/angelzubehor\/welsangeln\/welsrolle-angelzubehor.html\" target=\"_blank\" rel=\"noreferrer noopener\"> Welsrollen<\/a> zur\u00fcckgreifen, die f\u00fcr das Werfen und Spinnen konzipiert sind. Wenn du auf ein allgemeineres Modell zur\u00fcckgreifen m\u00f6chtest, kannst du es mit einer <a href=\"https:\/\/www.nootica.de\/marke\/daiwa-marke-angelausruestung\/daiwa-rollen.html\" target=\"_blank\" rel=\"noreferrer noopener\">Daiwa Spinnrolle<\/a> ausprobieren, oder auch mit einer <a href=\"https:\/\/www.nootica.de\/marke\/daiwa-marke-angelausruestung\/daiwa-rollen.html\" target=\"_blank\" rel=\"noreferrer noopener\">Daiwa Freilaufrolle<\/a>. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">F\u00fcr diese Art von <strong>K\u00f6derrolle<\/strong> bietet dir Daiwa eine gro\u00dfe Auswahl an M\u00f6glichkeiten. F\u00fcr den Anfang bekommst du eine Daiwa BG-Rolle f\u00fcr knapp unter 100 \u20ac. Wenn du ein echter Profi bist, kannst du es dir sogar leisten, \u00fcber 500 \u20ac f\u00fcr ein Saltiga Bay Jigging oder Catalina Bay Jigging auszugeben. Mit diesen Modellen wirst du sicher viel Spa\u00df beim Angeln haben. Wie du siehst, ist es am besten, wenn du auf den Kampf mit diesen riesigen Fischen gut vorbereitet bist.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hat dich auch das Angelfieber gepackt? Dann wei\u00dft du am besten, dass Angeln eine extrem spannende Aktivit\u00e4t ist. Es kann aber auch frustrierend sein, wenn du nicht den Fisch fangen kannst, den du willst. Das kann passieren, aber um das zu verhindern, solltest du dich f\u00fcr die richtige Ausr\u00fcstung entscheiden,<\/p>\n","protected":false},"author":1,"featured_media":234,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[106],"tags":[],"class_list":["post-368","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-angelrollen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Welche Daiwa-Rolle? - Fishing Star<\/title>\n<meta name=\"description\" content=\"Hat dich auch das Angelfieber gepackt? Dann wei\u00dft du am besten, dass Angeln eine extrem spannende Aktivit\u00e4t ist. Es kann auch\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fishing-star.com\/de\/index.php\/2021\/11\/04\/welche-daiwa-rolle\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Welche Daiwa-Rolle? - Fishing Star\" \/>\n<meta property=\"og:description\" content=\"Hat dich auch das Angelfieber gepackt? Dann wei\u00dft du am besten, dass Angeln eine extrem spannende Aktivit\u00e4t ist. Es kann auch\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fishing-star.com\/de\/index.php\/2021\/11\/04\/welche-daiwa-rolle\/\" \/>\n<meta property=\"og:site_name\" content=\"Fishing Star\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-04T13:48:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-03T09:13:15+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.fishing-star.com\/wp-content\/uploads\/2021\/10\/pexels-thirdman-5538151-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin3574\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin3574\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fishing-star.com\\\/de\\\/index.php\\\/2021\\\/11\\\/04\\\/welche-daiwa-rolle\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fishing-star.com\\\/de\\\/index.php\\\/2021\\\/11\\\/04\\\/welche-daiwa-rolle\\\/\"},\"author\":{\"name\":\"admin3574\",\"@id\":\"https:\\\/\\\/www.fishing-star.com\\\/it\\\/#\\\/schema\\\/person\\\/d317229a23db0356a2a24c9ff2eca908\"},\"headline\":\"Welche Daiwa-Rolle?\",\"datePublished\":\"2021-11-04T13:48:35+00:00\",\"dateModified\":\"2022-02-03T09:13:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fishing-star.com\\\/de\\\/index.php\\\/2021\\\/11\\\/04\\\/welche-daiwa-rolle\\\/\"},\"wordCount\":498,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.fishing-star.com\\\/de\\\/index.php\\\/2021\\\/11\\\/04\\\/welche-daiwa-rolle\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fishing-star.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/pexels-thirdman-5538151-1-scaled.jpg\",\"articleSection\":[\"Angelrollen\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.fishing-star.com\\\/de\\\/index.php\\\/2021\\\/11\\\/04\\\/welche-daiwa-rolle\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fishing-star.com\\\/de\\\/index.php\\\/2021\\\/11\\\/04\\\/welche-daiwa-rolle\\\/\",\"url\":\"https:\\\/\\\/www.fishing-star.com\\\/de\\\/index.php\\\/2021\\\/11\\\/04\\\/welche-daiwa-rolle\\\/\",\"name\":\"Welche Daiwa-Rolle? - Fishing Star\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fishing-star.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fishing-star.com\\\/de\\\/index.php\\\/2021\\\/11\\\/04\\\/welche-daiwa-rolle\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fishing-star.com\\\/de\\\/index.php\\\/2021\\\/11\\\/04\\\/welche-daiwa-rolle\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fishing-star.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/pexels-thirdman-5538151-1-scaled.jpg\",\"datePublished\":\"2021-11-04T13:48:35+00:00\",\"dateModified\":\"2022-02-03T09:13:15+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.fishing-star.com\\\/it\\\/#\\\/schema\\\/person\\\/d317229a23db0356a2a24c9ff2eca908\"},\"description\":\"Hat dich auch das Angelfieber gepackt? Dann wei\u00dft du am besten, dass Angeln eine extrem spannende Aktivit\u00e4t ist. Es kann auch\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fishing-star.com\\\/de\\\/index.php\\\/2021\\\/11\\\/04\\\/welche-daiwa-rolle\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fishing-star.com\\\/de\\\/index.php\\\/2021\\\/11\\\/04\\\/welche-daiwa-rolle\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.fishing-star.com\\\/de\\\/index.php\\\/2021\\\/11\\\/04\\\/welche-daiwa-rolle\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.fishing-star.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/pexels-thirdman-5538151-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.fishing-star.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/pexels-thirdman-5538151-1-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"moulinet daiwa\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fishing-star.com\\\/de\\\/index.php\\\/2021\\\/11\\\/04\\\/welche-daiwa-rolle\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.fishing-star.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Welche Daiwa-Rolle?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fishing-star.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.fishing-star.com\\\/it\\\/\",\"name\":\"Fishing Star\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fishing-star.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.fishing-star.com\\\/it\\\/#\\\/schema\\\/person\\\/d317229a23db0356a2a24c9ff2eca908\",\"name\":\"admin3574\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e0fbfb615b5d1b5ee2bc8c1bed1d7f792494b050a95e7848e61de9f6791cb3d3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e0fbfb615b5d1b5ee2bc8c1bed1d7f792494b050a95e7848e61de9f6791cb3d3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e0fbfb615b5d1b5ee2bc8c1bed1d7f792494b050a95e7848e61de9f6791cb3d3?s=96&d=mm&r=g\",\"caption\":\"admin3574\"},\"sameAs\":[\"http:\\\/\\\/www.fishing-star.com\"],\"url\":\"https:\\\/\\\/www.fishing-star.com\\\/de\\\/index.php\\\/author\\\/admin3574\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Welche Daiwa-Rolle? - Fishing Star","description":"Hat dich auch das Angelfieber gepackt? Dann wei\u00dft du am besten, dass Angeln eine extrem spannende Aktivit\u00e4t ist. Es kann auch","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fishing-star.com\/de\/index.php\/2021\/11\/04\/welche-daiwa-rolle\/","og_locale":"de_DE","og_type":"article","og_title":"Welche Daiwa-Rolle? - Fishing Star","og_description":"Hat dich auch das Angelfieber gepackt? Dann wei\u00dft du am besten, dass Angeln eine extrem spannende Aktivit\u00e4t ist. Es kann auch","og_url":"https:\/\/www.fishing-star.com\/de\/index.php\/2021\/11\/04\/welche-daiwa-rolle\/","og_site_name":"Fishing Star","article_published_time":"2021-11-04T13:48:35+00:00","article_modified_time":"2022-02-03T09:13:15+00:00","og_image":[{"width":2560,"height":1707,"url":"http:\/\/www.fishing-star.com\/wp-content\/uploads\/2021\/10\/pexels-thirdman-5538151-1-scaled.jpg","type":"image\/jpeg"}],"author":"admin3574","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"admin3574","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fishing-star.com\/de\/index.php\/2021\/11\/04\/welche-daiwa-rolle\/#article","isPartOf":{"@id":"https:\/\/www.fishing-star.com\/de\/index.php\/2021\/11\/04\/welche-daiwa-rolle\/"},"author":{"name":"admin3574","@id":"https:\/\/www.fishing-star.com\/it\/#\/schema\/person\/d317229a23db0356a2a24c9ff2eca908"},"headline":"Welche Daiwa-Rolle?","datePublished":"2021-11-04T13:48:35+00:00","dateModified":"2022-02-03T09:13:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fishing-star.com\/de\/index.php\/2021\/11\/04\/welche-daiwa-rolle\/"},"wordCount":498,"commentCount":0,"image":{"@id":"https:\/\/www.fishing-star.com\/de\/index.php\/2021\/11\/04\/welche-daiwa-rolle\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fishing-star.com\/wp-content\/uploads\/2021\/10\/pexels-thirdman-5538151-1-scaled.jpg","articleSection":["Angelrollen"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fishing-star.com\/de\/index.php\/2021\/11\/04\/welche-daiwa-rolle\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fishing-star.com\/de\/index.php\/2021\/11\/04\/welche-daiwa-rolle\/","url":"https:\/\/www.fishing-star.com\/de\/index.php\/2021\/11\/04\/welche-daiwa-rolle\/","name":"Welche Daiwa-Rolle? - Fishing Star","isPartOf":{"@id":"https:\/\/www.fishing-star.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fishing-star.com\/de\/index.php\/2021\/11\/04\/welche-daiwa-rolle\/#primaryimage"},"image":{"@id":"https:\/\/www.fishing-star.com\/de\/index.php\/2021\/11\/04\/welche-daiwa-rolle\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fishing-star.com\/wp-content\/uploads\/2021\/10\/pexels-thirdman-5538151-1-scaled.jpg","datePublished":"2021-11-04T13:48:35+00:00","dateModified":"2022-02-03T09:13:15+00:00","author":{"@id":"https:\/\/www.fishing-star.com\/it\/#\/schema\/person\/d317229a23db0356a2a24c9ff2eca908"},"description":"Hat dich auch das Angelfieber gepackt? Dann wei\u00dft du am besten, dass Angeln eine extrem spannende Aktivit\u00e4t ist. Es kann auch","breadcrumb":{"@id":"https:\/\/www.fishing-star.com\/de\/index.php\/2021\/11\/04\/welche-daiwa-rolle\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fishing-star.com\/de\/index.php\/2021\/11\/04\/welche-daiwa-rolle\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.fishing-star.com\/de\/index.php\/2021\/11\/04\/welche-daiwa-rolle\/#primaryimage","url":"https:\/\/www.fishing-star.com\/wp-content\/uploads\/2021\/10\/pexels-thirdman-5538151-1-scaled.jpg","contentUrl":"https:\/\/www.fishing-star.com\/wp-content\/uploads\/2021\/10\/pexels-thirdman-5538151-1-scaled.jpg","width":2560,"height":1707,"caption":"moulinet daiwa"},{"@type":"BreadcrumbList","@id":"https:\/\/www.fishing-star.com\/de\/index.php\/2021\/11\/04\/welche-daiwa-rolle\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.fishing-star.com\/it\/"},{"@type":"ListItem","position":2,"name":"Welche Daiwa-Rolle?"}]},{"@type":"WebSite","@id":"https:\/\/www.fishing-star.com\/it\/#website","url":"https:\/\/www.fishing-star.com\/it\/","name":"Fishing Star","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fishing-star.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.fishing-star.com\/it\/#\/schema\/person\/d317229a23db0356a2a24c9ff2eca908","name":"admin3574","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/e0fbfb615b5d1b5ee2bc8c1bed1d7f792494b050a95e7848e61de9f6791cb3d3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e0fbfb615b5d1b5ee2bc8c1bed1d7f792494b050a95e7848e61de9f6791cb3d3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e0fbfb615b5d1b5ee2bc8c1bed1d7f792494b050a95e7848e61de9f6791cb3d3?s=96&d=mm&r=g","caption":"admin3574"},"sameAs":["http:\/\/www.fishing-star.com"],"url":"https:\/\/www.fishing-star.com\/de\/index.php\/author\/admin3574\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.fishing-star.com\/de\/index.php\/wp-json\/wp\/v2\/posts\/368","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fishing-star.com\/de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fishing-star.com\/de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fishing-star.com\/de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fishing-star.com\/de\/index.php\/wp-json\/wp\/v2\/comments?post=368"}],"version-history":[{"count":5,"href":"https:\/\/www.fishing-star.com\/de\/index.php\/wp-json\/wp\/v2\/posts\/368\/revisions"}],"predecessor-version":[{"id":1078,"href":"https:\/\/www.fishing-star.com\/de\/index.php\/wp-json\/wp\/v2\/posts\/368\/revisions\/1078"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fishing-star.com\/de\/index.php\/wp-json\/wp\/v2\/media\/234"}],"wp:attachment":[{"href":"https:\/\/www.fishing-star.com\/de\/index.php\/wp-json\/wp\/v2\/media?parent=368"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fishing-star.com\/de\/index.php\/wp-json\/wp\/v2\/categories?post=368"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fishing-star.com\/de\/index.php\/wp-json\/wp\/v2\/tags?post=368"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}